{"id":3769,"date":"2017-05-16T07:49:38","date_gmt":"2017-05-16T07:49:38","guid":{"rendered":"http:\/\/hydraulics.unibs.it\/hydraulics\/?p=3769"},"modified":"2017-05-16T07:49:38","modified_gmt":"2017-05-16T07:49:38","slug":"prof-bernard-laval-is-visiting-professor-at-dicatam","status":"publish","type":"post","link":"https:\/\/hydraulics.unibs.it\/hydraulics\/prof-bernard-laval-is-visiting-professor-at-dicatam\/","title":{"rendered":"Prof. Bernard Laval is visiting professor at DICATAM"},"content":{"rendered":"<p>Prof. Bernard Laval from University of British Columbia, Vancouver, Canada,\u00a0will be visiting Professor at DICATAM, guest\u00a0of the hydraulics group. He will deliver a set of seminars on physical limnology and will collaborate on the research activities\u00a0regarding the hydrodynamic of deep lakes.<\/p>\n<div id=\"metaslider-id-3723\" style=\"max-width: 700px;\" class=\"ml-slider-3-109-0 metaslider metaslider-flex metaslider-3723 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Laval\" data-height=\"500\" data-width=\"700\">\n    <div id=\"metaslider_container_3723\">\n        <div id=\"metaslider_3723\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-3778 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-05-16 07:44:51\" data-filename=\"20170511_103158-700x500.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-content\/uploads\/2017\/05\/20170511_103158-700x500.jpg\" height=\"500\" width=\"700\" alt=\"\" class=\"slider-3723 slide-3778 msDefaultImage\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3777 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-05-16 07:44:51\" data-filename=\"20170511_103207-e1494920476314-700x500.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-content\/uploads\/2017\/05\/20170511_103207-e1494920476314-700x500.jpg\" height=\"500\" width=\"700\" alt=\"\" class=\"slider-3723 slide-3777 msDefaultImage\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3776 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-05-16 07:44:51\" data-filename=\"20170510_132338-700x500.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-content\/uploads\/2017\/05\/20170510_132338-700x500.jpg\" height=\"500\" width=\"700\" alt=\"\" class=\"slider-3723 slide-3776 msDefaultImage\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3779 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-05-16 07:44:51\" data-filename=\"20170510_123121-e1494920511710-700x500.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-content\/uploads\/2017\/05\/20170510_123121-e1494920511710-700x500.jpg\" height=\"500\" width=\"700\" alt=\"\" class=\"slider-3723 slide-3779 msDefaultImage\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prof. Bernard Laval from University of British Columbia, Vancouver, Canada,\u00a0will be visiting Professor at DICATAM, guest\u00a0of the hydraulics group. He will deliver a set of seminars on physical limnology and will collaborate on the research activities\u00a0regarding the hydrodynamic of deep lakes. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3769","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/posts\/3769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/comments?post=3769"}],"version-history":[{"count":2,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/posts\/3769\/revisions"}],"predecessor-version":[{"id":3780,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/posts\/3769\/revisions\/3780"}],"wp:attachment":[{"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/media?parent=3769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/categories?post=3769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hydraulics.unibs.it\/hydraulics\/wp-json\/wp\/v2\/tags?post=3769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}